{"id":14141,"date":"2022-03-10T13:28:58","date_gmt":"2022-03-10T18:28:58","guid":{"rendered":"https:\/\/sarayaku.org\/?p=14141"},"modified":"2026-05-28T12:08:41","modified_gmt":"2026-05-28T17:08:41","slug":"la-fruta-amazonica-con-historia-wituk","status":"publish","type":"post","link":"https:\/\/sarayaku.org\/en\/la-fruta-amazonica-con-historia-wituk\/","title":{"rendered":"The Amazonian fruit with history, Wituk"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section class=\"vc_section vc_custom_1646936228106 vc_section-has-fill\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center;\"><span style=\"font-size: 60px; color: #ffffff; font-family: georgia, palatino, serif;\">La fruta amaz\u00f3nica con historia, Wituk<\/span><\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1647998849299\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #ffffff; font-size: 24px;\">El <a style=\"color: #ffffff;\" href=\"https:\/\/es.wikipedia.org\/wiki\/Genipa_americana\" target=\"_blank\" rel=\"noopener\">wituk<\/a> es una fruta amaz\u00f3nica de un \u00e1rbol, utilizada para el tratamiento natural para cabello, pintarse la cara y el cuerpo. Adem\u00e1s, es usada para los rituales de pintura en la fiesta tradicional de Sarayaku (Uyantza). El wituk es parte integral de la vestimenta de los Kichwa Runa<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 24px; color: #ffffff;\">En tiempos antiguos, cuentan que el wituk era una hermosa mujer que, despu\u00e9s de una decepci\u00f3n sentimental, se convirti\u00f3 en \u00e1rbol de wituk \u00a0para dar \u00e1nimo,\u00a0 y\u00a0 felicidad a todas las mujeres y hombres de la tierra pint\u00e1ndose \u00a0la cara con su fruta.<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 24px; color: #ffffff;\">La Mujer wituk tiene su hermana, Manduro (achiote), que igual que ella por una decepci\u00f3n se convirti\u00f3 en el \u00e1rbol de achiote; juntas pintaron a todas las aves, p\u00e1jaros y animales que existen en la Amazon\u00eda, d\u00e1ndole color y alegr\u00eda. <\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Usos del Wituk<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"font-size: 24px; color: #ffffff;\">Para pintarse, se corta la parte superior de esta fruta amaz\u00f3nica, se remueve el interior con un cuchillo, y se asa a fuego lento hasta que la pulpa se vuelva negra. En ese exprime el fruto para recuperar el l\u00edquido. <\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1647998929843\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"font-size: 24px; color: #ffffff;\">Las partes del cuerpo se pintan con algod\u00f3n; y, para las pinturas faciales se utilizan finos palitos de inayu (palma). Para el cabello, se ralla la fruta con una shiquita (ralladora natural que es es extraida de la palma llamada chingu); luego se exprime su jugo poco a poco en el cabello hasta que quede todo humedecido con el l\u00edquido, este proceso se realiza tres veces al d\u00eda durante tres d\u00edas sin enjuagarse en el agua.<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 24px; color: #ffffff;\">Wituk la utilizamos en cada fiesta, en cada minga, los d\u00edas domingos \u00a0cuando tenemos chichita en nuestras casas o en otros eventos importantes; las mujeres y los hombres de Sarayaku nos pintamos la cara de wituk para honrar y recordar la belleza de la Mujer Wituk. Adem\u00e1s cada dise\u00f1o simboliza a seres de la selva y animales fuertes que poseen energ\u00edas como la anaconda, el puma y otros animales. <\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 24px; color: #ffffff;\">El Wituk es una expresi\u00f3n propia de Sarayaku que manifiesta la coexistencia intr\u00ednseca con la Selva Viviente &#8211; Kawsak Sacha<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>[kleo_gap size=&#8221;30px&#8221;]\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"206\" src=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-scaled.png\" class=\"vc_single_image-img attachment-full\" alt=\"vector 3\" title=\"2\" srcset=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-scaled.png 2560w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-18x1.png 18w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-300x24.png 300w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-768x62.png 768w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-1024x82.png 1024w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-1536x124.png 1536w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-2048x165.png 2048w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-510x41.png 510w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-672x54.png 672w, https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/2-1-1038x84.png 1038w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Imagen cr\u00e9dito Misha Vallejo<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-size: 24px;\">Lee otras historias de Sarayaku en nuestra secci\u00f3n <strong><a href=\"https:\/\/sarayaku.org\/category\/sarayaku-kikin-kawsay-culturales\/\">Sarayaku kikin kawsay.<\/a><\/strong><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"La fruta amaz\u00f3nica con historia, Wituk El wituk es una fruta amaz\u00f3nica de un \u00e1rbol, utilizada para el tratamiento natural para cabello, pintarse la cara y el cuerpo. Adem\u00e1s, es usada para los rituales de pintura en la fiesta tradicional de Sarayaku (Uyantza). El wituk es parte integral de la vestimenta de los Kichwa Runa [...]","protected":false},"author":1,"featured_media":14230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[135],"tags":[],"class_list":["post-14141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sarayaku-kikin-kawsay-culturales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La fruta amaz\u00f3nica con historia, Wituk<\/title>\n<meta name=\"description\" content=\"Wituk, fruta amaz\u00f3nica que es utilizada por el Pueblo Originario Kichwa de Sarayaku del Ecuador para el tratamiento natural del cabello.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sarayaku.org\/en\/la-fruta-amazonica-con-historia-wituk\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fruta amaz\u00f3nica con historia, Wituk\" \/>\n<meta property=\"og:description\" content=\"Wituk, fruta amaz\u00f3nica que es utilizada por el Pueblo Originario Kichwa de Sarayaku del Ecuador para el tratamiento natural del cabello.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sarayaku.org\/en\/la-fruta-amazonica-con-historia-wituk\/\" \/>\n<meta property=\"og:site_name\" content=\"Pueblo Originario Kichwa de Sarayaku\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T18:28:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T17:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/E5AHbLbWYAU7qUU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sarayaku\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sarayaku\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/\"},\"author\":{\"name\":\"sarayaku\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#\\\/schema\\\/person\\\/e6707433124023cdf0b5cd12db508b51\"},\"headline\":\"La fruta amaz\u00f3nica con historia, Wituk\",\"datePublished\":\"2022-03-10T18:28:58+00:00\",\"dateModified\":\"2026-05-28T17:08:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/\"},\"wordCount\":545,\"image\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/E5AHbLbWYAU7qUU.jpg\",\"articleSection\":[\"Sarayaku Kikin Kawsay (Culturales)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/\",\"url\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/\",\"name\":\"La fruta amaz\u00f3nica con historia, Wituk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/E5AHbLbWYAU7qUU.jpg\",\"datePublished\":\"2022-03-10T18:28:58+00:00\",\"dateModified\":\"2026-05-28T17:08:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#\\\/schema\\\/person\\\/e6707433124023cdf0b5cd12db508b51\"},\"description\":\"Wituk, fruta amaz\u00f3nica que es utilizada por el Pueblo Originario Kichwa de Sarayaku del Ecuador para el tratamiento natural del cabello.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/E5AHbLbWYAU7qUU.jpg\",\"contentUrl\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/E5AHbLbWYAU7qUU.jpg\",\"width\":768,\"height\":960,\"caption\":\"tratamiento para cabello con el wituk, fruta amaz\u00f3nica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/la-fruta-amazonica-con-historia-wituk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sarayaku.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La fruta amaz\u00f3nica con historia, Wituk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#website\",\"url\":\"https:\\\/\\\/sarayaku.org\\\/\",\"name\":\"Pueblo Originario Kichwa de Sarayaku\",\"description\":\"El Pueblo del Mediod\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sarayaku.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#\\\/schema\\\/person\\\/e6707433124023cdf0b5cd12db508b51\",\"name\":\"sarayaku\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g\",\"caption\":\"sarayaku\"},\"url\":\"https:\\\/\\\/sarayaku.org\\\/en\\\/author\\\/sarayaku\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Amazonian fruit with history, Wituk","description":"Wituk, an Amazonian fruit used by the Kichwa Indigenous People of Sarayaku in Ecuador for natural hair treatment.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sarayaku.org\/en\/la-fruta-amazonica-con-historia-wituk\/","og_locale":"en_US","og_type":"article","og_title":"La fruta amaz\u00f3nica con historia, Wituk","og_description":"Wituk, fruta amaz\u00f3nica que es utilizada por el Pueblo Originario Kichwa de Sarayaku del Ecuador para el tratamiento natural del cabello.","og_url":"https:\/\/sarayaku.org\/en\/la-fruta-amazonica-con-historia-wituk\/","og_site_name":"Pueblo Originario Kichwa de Sarayaku","article_published_time":"2022-03-10T18:28:58+00:00","article_modified_time":"2026-05-28T17:08:41+00:00","og_image":[{"width":768,"height":960,"url":"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/E5AHbLbWYAU7qUU.jpg","type":"image\/jpeg"}],"author":"sarayaku","twitter_misc":{"Written by":"sarayaku","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/#article","isPartOf":{"@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/"},"author":{"name":"sarayaku","@id":"https:\/\/sarayaku.org\/#\/schema\/person\/e6707433124023cdf0b5cd12db508b51"},"headline":"La fruta amaz\u00f3nica con historia, Wituk","datePublished":"2022-03-10T18:28:58+00:00","dateModified":"2026-05-28T17:08:41+00:00","mainEntityOfPage":{"@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/"},"wordCount":545,"image":{"@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/#primaryimage"},"thumbnailUrl":"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/E5AHbLbWYAU7qUU.jpg","articleSection":["Sarayaku Kikin Kawsay (Culturales)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/","url":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/","name":"The Amazonian fruit with history, Wituk","isPartOf":{"@id":"https:\/\/sarayaku.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/#primaryimage"},"image":{"@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/#primaryimage"},"thumbnailUrl":"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/E5AHbLbWYAU7qUU.jpg","datePublished":"2022-03-10T18:28:58+00:00","dateModified":"2026-05-28T17:08:41+00:00","author":{"@id":"https:\/\/sarayaku.org\/#\/schema\/person\/e6707433124023cdf0b5cd12db508b51"},"description":"Wituk, an Amazonian fruit used by the Kichwa Indigenous People of Sarayaku in Ecuador for natural hair treatment.","breadcrumb":{"@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/#primaryimage","url":"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/E5AHbLbWYAU7qUU.jpg","contentUrl":"https:\/\/sarayaku.org\/wp-content\/uploads\/2022\/03\/E5AHbLbWYAU7qUU.jpg","width":768,"height":960,"caption":"tratamiento para cabello con el wituk, fruta amaz\u00f3nica"},{"@type":"BreadcrumbList","@id":"https:\/\/sarayaku.org\/la-fruta-amazonica-con-historia-wituk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sarayaku.org\/"},{"@type":"ListItem","position":2,"name":"La fruta amaz\u00f3nica con historia, Wituk"}]},{"@type":"WebSite","@id":"https:\/\/sarayaku.org\/#website","url":"https:\/\/sarayaku.org\/","name":"Original Kichwa People of Sarayaku","description":"The Town of the South","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sarayaku.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sarayaku.org\/#\/schema\/person\/e6707433124023cdf0b5cd12db508b51","name":"sarayaku","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g","caption":"sarayaku"},"url":"https:\/\/sarayaku.org\/en\/author\/sarayaku\/"}]}},"_links":{"self":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/posts\/14141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/comments?post=14141"}],"version-history":[{"count":1,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/posts\/14141\/revisions"}],"predecessor-version":[{"id":16102,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/posts\/14141\/revisions\/16102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/media\/14230"}],"wp:attachment":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/media?parent=14141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/categories?post=14141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/tags?post=14141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}