{"id":2087,"date":"2014-02-05T17:26:15","date_gmt":"2014-02-05T17:26:15","guid":{"rendered":"https:\/\/sarayaku.org\/?p=2087"},"modified":"2014-02-06T04:06:06","modified_gmt":"2014-02-06T04:06:06","slug":"encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza","status":"publish","type":"post","link":"https:\/\/sarayaku.org\/en\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/","title":{"rendered":"Meeting of integration and fellowship of Peoples and Nationalities of the province of Pastaza"},"content":{"rendered":"<p style=\"text-align: center;\" align=\"center\"><b>INVITATION<\/b><\/p>\n<p style=\"text-align: left;\">The Kichwa People of Sarayaku, in coordination with the Pachakutik Plurinational Unity movement, have the honor of inviting all the compa\u00f1eras and compa\u00f1eros from the seven Nationalities and the Peoples of the Ecuadorian Highlands who live in the city of Puyo and its surroundings to the great <b>Meeting of Integration and Brotherhood of Peoples and Nationalities<\/b> with the following objectives:<\/p>\n<p style=\"text-align: left;\">\u2013 Promote the integration and social, cultural, economic, political and organizational unity of the Peoples and Nationalities of the Province of Pastaza.<\/p>\n<p style=\"text-align: left;\">\u2013 Consolidate the Pachakutik Plurinational Unity Movement as a tool for political participation and exercise of the rights of Peoples and Nationalities.<\/p>\n<p style=\"text-align: left;\">The event will take place on February 8, 2014, at the Mexico Complex, Calle 9 de Octubre, next to the Comptroller General of the State. Below is the meeting schedule.<\/p>\n<p align=\"center\"><b>EVENT SCHEDULE<\/b><\/p>\n<p style=\"text-align: center;\" align=\"center\"><a href=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.18.33.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2088 aligncenter\" style=\"border: 1px solid black; margin-top: 2px; margin-bottom: 2px;\" alt=\"Captura de pantalla 2014-02-05 a la(s) 12.18.33\" src=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.18.33.png\" width=\"541\" height=\"361\" srcset=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.18.33.png 751w, https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.18.33-510x340.png 510w, https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.18.33-300x200.png 300w\" sizes=\"auto, (max-width: 541px) 100vw, 541px\" \/><\/a><\/p>\n<p style=\"text-align: center;\" align=\"center\"><a href=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.22.29.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2089 aligncenter\" style=\"border: 1px solid black; margin-top: 2px; margin-bottom: 2px;\" alt=\"Captura de pantalla 2014-02-05 a la(s) 12.22.29\" src=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.22.29.png\" width=\"534\" height=\"277\" srcset=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.22.29.png 741w, https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.22.29-510x265.png 510w, https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/Captura-de-pantalla-2014-02-05-a-las-12.22.29-300x155.png 300w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/a><\/p>\n<p><strong>More information call: 0984833655 Jhonny Dahua \u2013 Responsible<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>INVITACION El Pueblo Kichwa de Sarayaku en coordinaci\u00f3n con el movimiento de Unidad Plurinacional Pachakutik tienen el honor de invitar a todas las compa\u00f1eras y compa\u00f1eros de las siete Nacionalidades y de los Pueblos de la Serran\u00eda Ecuatoriana que habitan en la ciudad de Puyo y sus alrededores al gran Encuentro de Integraci\u00f3n y Confraternidad [&#8230;]\n","protected":false},"author":1,"featured_media":2090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[9,25],"tags":[],"class_list":["post-2087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-organizativas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza - Pueblo Originario Kichwa de Sarayaku<\/title>\n<meta name=\"description\" content=\"Sarayaku, Pueblo Originario Kichwa del Medio D\u00eda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sarayaku.org\/en\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza\" \/>\n<meta property=\"og:description\" content=\"Sarayaku, Pueblo Originario Kichwa del Medio D\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sarayaku.org\/en\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/\" \/>\n<meta property=\"og:site_name\" content=\"Pueblo Originario Kichwa de Sarayaku\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-05T17:26:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-06T04:06:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sarayaku\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sarayaku\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/\"},\"author\":{\"name\":\"sarayaku\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#\\\/schema\\\/person\\\/e6707433124023cdf0b5cd12db508b51\"},\"headline\":\"Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza\",\"datePublished\":\"2014-02-05T17:26:15+00:00\",\"dateModified\":\"2014-02-06T04:06:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/\"},\"wordCount\":177,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/22.jpg\",\"articleSection\":[\"Noticias\",\"Organizativas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/\",\"url\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/\",\"name\":\"Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza - Pueblo Originario Kichwa de Sarayaku\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/22.jpg\",\"datePublished\":\"2014-02-05T17:26:15+00:00\",\"dateModified\":\"2014-02-06T04:06:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#\\\/schema\\\/person\\\/e6707433124023cdf0b5cd12db508b51\"},\"description\":\"Sarayaku, Pueblo Originario Kichwa del Medio D\u00eda\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/22.jpg\",\"contentUrl\":\"https:\\\/\\\/sarayaku.org\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/22.jpg\",\"width\":448,\"height\":301},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sarayaku.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#website\",\"url\":\"https:\\\/\\\/sarayaku.org\\\/\",\"name\":\"Pueblo Originario Kichwa de Sarayaku\",\"description\":\"El Pueblo del Mediod\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sarayaku.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sarayaku.org\\\/#\\\/schema\\\/person\\\/e6707433124023cdf0b5cd12db508b51\",\"name\":\"sarayaku\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g\",\"caption\":\"sarayaku\"},\"url\":\"https:\\\/\\\/sarayaku.org\\\/en\\\/author\\\/sarayaku\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Meeting for integration and fraternity of the Peoples and Nationalities of the province of Pastaza - Kichwa Indigenous People of Sarayaku","description":"Sarayaku, Kichwa Native Village of Midday","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sarayaku.org\/en\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/","og_locale":"en_US","og_type":"article","og_title":"Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza","og_description":"Sarayaku, Pueblo Originario Kichwa del Medio D\u00eda","og_url":"https:\/\/sarayaku.org\/en\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/","og_site_name":"Pueblo Originario Kichwa de Sarayaku","article_published_time":"2014-02-05T17:26:15+00:00","article_modified_time":"2014-02-06T04:06:06+00:00","og_image":[{"width":448,"height":301,"url":"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/22.jpg","type":"image\/jpeg"}],"author":"sarayaku","twitter_misc":{"Written by":"sarayaku","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#article","isPartOf":{"@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/"},"author":{"name":"sarayaku","@id":"https:\/\/sarayaku.org\/#\/schema\/person\/e6707433124023cdf0b5cd12db508b51"},"headline":"Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza","datePublished":"2014-02-05T17:26:15+00:00","dateModified":"2014-02-06T04:06:06+00:00","mainEntityOfPage":{"@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/"},"wordCount":177,"commentCount":0,"image":{"@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#primaryimage"},"thumbnailUrl":"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/22.jpg","articleSection":["Noticias","Organizativas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/","url":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/","name":"Meeting for integration and fraternity of the Peoples and Nationalities of the province of Pastaza - Kichwa Indigenous People of Sarayaku","isPartOf":{"@id":"https:\/\/sarayaku.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#primaryimage"},"image":{"@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#primaryimage"},"thumbnailUrl":"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/22.jpg","datePublished":"2014-02-05T17:26:15+00:00","dateModified":"2014-02-06T04:06:06+00:00","author":{"@id":"https:\/\/sarayaku.org\/#\/schema\/person\/e6707433124023cdf0b5cd12db508b51"},"description":"Sarayaku, Kichwa Native Village of Midday","breadcrumb":{"@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#primaryimage","url":"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/22.jpg","contentUrl":"https:\/\/sarayaku.org\/wp-content\/uploads\/2014\/02\/22.jpg","width":448,"height":301},{"@type":"BreadcrumbList","@id":"https:\/\/sarayaku.org\/encuentro-de-integracion-y-confraternidad-de-los-pueblos-y-nacionalidades-de-la-provincia-de-pastaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sarayaku.org\/"},{"@type":"ListItem","position":2,"name":"Encuentro de integraci\u00f3n y confraternidad de Pueblos y Nacionalidades de la provincia de Pastaza"}]},{"@type":"WebSite","@id":"https:\/\/sarayaku.org\/#website","url":"https:\/\/sarayaku.org\/","name":"Original Kichwa People of Sarayaku","description":"The Town of the South","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sarayaku.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sarayaku.org\/#\/schema\/person\/e6707433124023cdf0b5cd12db508b51","name":"sarayaku","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/350b458bf2e7e2b8d04c231493a7e76da645d77eb32eedbd572036312548c539?s=96&r=g","caption":"sarayaku"},"url":"https:\/\/sarayaku.org\/en\/author\/sarayaku\/"}]}},"_links":{"self":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/posts\/2087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/comments?post=2087"}],"version-history":[{"count":0,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/posts\/2087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/media\/2090"}],"wp:attachment":[{"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/media?parent=2087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/categories?post=2087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sarayaku.org\/en\/wp-json\/wp\/v2\/tags?post=2087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}